{"id":6700,"date":"2024-09-23T09:49:15","date_gmt":"2024-09-23T07:49:15","guid":{"rendered":"https:\/\/www.adosa.es\/blog\/?p=6700"},"modified":"2024-09-04T17:13:31","modified_gmt":"2024-09-04T15:13:31","slug":"restauracion-bancos","status":"publish","type":"post","link":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/","title":{"rendered":"Restauraci\u00f3n Bancos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con motivo de la&nbsp;celebraci\u00f3n&nbsp;de la prestigiosa COPA&nbsp;AM\u00c9RICA&nbsp;en la ciudad de Barcelona, se nos ha solicitado realizar una&nbsp;restauraci\u00f3n&nbsp;de mobiliario urbano en especial de Bancos, con el fin de mejorar el aspecto la ciudad para que los ciudadanos y visitantes disfruten de la belleza y el encanto de una ciudad como Barcelona.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"6702\" src=\"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog1-1024x1024.jpg\" alt=\"\" class=\"wp-image-6702\" srcset=\"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog1-1024x1024.jpg 1024w, https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog1-300x300.jpg 300w, https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog1-150x150.jpg 150w, https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog1-768x768.jpg 768w, https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"6701\" src=\"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog2-1024x1024.jpg\" alt=\"\" class=\"wp-image-6701\" srcset=\"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog2-1024x1024.jpg 1024w, https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog2-300x300.jpg 300w, https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog2-150x150.jpg 150w, https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog2-768x768.jpg 768w, https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El trabajo se ha realizado en un tiempo&nbsp;r\u00e9cord, desmontado los bancos en mal estado, restaur\u00e1ndolos en taller, realizando trabajos de&nbsp;substituci\u00f3n&nbsp;de maderas en mal estado, fresado, lijado, barnizado, reforzar estos, barnizar e instalar nuevamente en obra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De una manera sostenible hemos conseguido renovar el mobiliario de una ciudad como Barcelona. <\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"854\" style=\"aspect-ratio: 480 \/ 854;\" width=\"480\" controls src=\"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/reel-reparacion.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo de la&nbsp;celebraci\u00f3n&nbsp;de la prestigiosa COPA&nbsp;AM\u00c9RICA&nbsp;en la ciudad de Barcelona, se nos ha solicitado realizar una&nbsp;restauraci\u00f3n&nbsp;de mobiliario urbano en especial de Bancos, con el fin de mejorar el aspecto la ciudad para que los ciudadanos y visitantes disfruten de la belleza y el encanto de una ciudad como Barcelona. El trabajo se ha realizado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6701,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78],"tags":[],"class_list":["post-6700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bancos-urbanos-mobiliario-urbano-ado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restauraci\u00f3n Bancos - ADO Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restauraci\u00f3n Bancos - ADO Blog\" \/>\n<meta property=\"og:description\" content=\"Con motivo de la&nbsp;celebraci\u00f3n&nbsp;de la prestigiosa COPA&nbsp;AM\u00c9RICA&nbsp;en la ciudad de Barcelona, se nos ha solicitado realizar una&nbsp;restauraci\u00f3n&nbsp;de mobiliario urbano en especial de Bancos, con el fin de mejorar el aspecto la ciudad para que los ciudadanos y visitantes disfruten de la belleza y el encanto de una ciudad como Barcelona. El trabajo se ha realizado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/\" \/>\n<meta property=\"og:site_name\" content=\"ADO Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adobcn1\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-23T07:49:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adosa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Adobcn\" \/>\n<meta name=\"twitter:site\" content=\"@Adobcn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/restauracion-bancos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/restauracion-bancos\\\/\"},\"author\":{\"name\":\"adosa\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#\\\/schema\\\/person\\\/81eafc1325fbcc103884a7dfefe3802d\"},\"headline\":\"Restauraci\u00f3n Bancos\",\"datePublished\":\"2024-09-23T07:49:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/restauracion-bancos\\\/\"},\"wordCount\":126,\"publisher\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/restauracion-bancos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/blog2.jpg\",\"articleSection\":[\"Bancos urbanos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/restauracion-bancos\\\/\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/restauracion-bancos\\\/\",\"name\":\"Restauraci\u00f3n Bancos - ADO Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/restauracion-bancos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/restauracion-bancos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/blog2.jpg\",\"datePublished\":\"2024-09-23T07:49:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/restauracion-bancos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.adosa.es\\\/blog\\\/restauracion-bancos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/restauracion-bancos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/blog2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/blog2.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/restauracion-bancos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restauraci\u00f3n Bancos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/\",\"name\":\"ADO Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#organization\"},\"alternateName\":\"Ado blog corporativo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#organization\",\"name\":\"ADO Blog\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ado.png\",\"contentUrl\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ado.png\",\"width\":193,\"height\":101,\"caption\":\"ADO Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adobcn1\\\/\",\"https:\\\/\\\/x.com\\\/Adobcn\",\"https:\\\/\\\/www.instagram.com\\\/ado_cerramientos_metalicos\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/adocerramientosmetalicos\",\"https:\\\/\\\/www.pinterest.es\\\/adocerramientos\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2141531\\\/admin\\\/feed\\\/posts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/adosa2010\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#\\\/schema\\\/person\\\/81eafc1325fbcc103884a7dfefe3802d\",\"name\":\"adosa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g\",\"caption\":\"adosa\"},\"sameAs\":[\"https:\\\/\\\/www.adosa.es\\\/blog\"],\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/author\\\/adosa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restauraci\u00f3n Bancos - ADO Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/","og_locale":"es_ES","og_type":"article","og_title":"Restauraci\u00f3n Bancos - ADO Blog","og_description":"Con motivo de la&nbsp;celebraci\u00f3n&nbsp;de la prestigiosa COPA&nbsp;AM\u00c9RICA&nbsp;en la ciudad de Barcelona, se nos ha solicitado realizar una&nbsp;restauraci\u00f3n&nbsp;de mobiliario urbano en especial de Bancos, con el fin de mejorar el aspecto la ciudad para que los ciudadanos y visitantes disfruten de la belleza y el encanto de una ciudad como Barcelona. El trabajo se ha realizado [&hellip;]","og_url":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/","og_site_name":"ADO Blog","article_publisher":"https:\/\/www.facebook.com\/adobcn1\/","article_published_time":"2024-09-23T07:49:15+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog2.jpg","type":"image\/jpeg"}],"author":"adosa","twitter_card":"summary_large_image","twitter_creator":"@Adobcn","twitter_site":"@Adobcn","twitter_misc":{"Escrito por":"adosa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/#article","isPartOf":{"@id":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/"},"author":{"name":"adosa","@id":"https:\/\/www.adosa.es\/blog\/#\/schema\/person\/81eafc1325fbcc103884a7dfefe3802d"},"headline":"Restauraci\u00f3n Bancos","datePublished":"2024-09-23T07:49:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/"},"wordCount":126,"publisher":{"@id":"https:\/\/www.adosa.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog2.jpg","articleSection":["Bancos urbanos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/","url":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/","name":"Restauraci\u00f3n Bancos - ADO Blog","isPartOf":{"@id":"https:\/\/www.adosa.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/#primaryimage"},"image":{"@id":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog2.jpg","datePublished":"2024-09-23T07:49:15+00:00","breadcrumb":{"@id":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adosa.es\/blog\/restauracion-bancos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/#primaryimage","url":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog2.jpg","contentUrl":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2024\/09\/blog2.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.adosa.es\/blog\/restauracion-bancos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.adosa.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Restauraci\u00f3n Bancos"}]},{"@type":"WebSite","@id":"https:\/\/www.adosa.es\/blog\/#website","url":"https:\/\/www.adosa.es\/blog\/","name":"ADO Blog","description":"","publisher":{"@id":"https:\/\/www.adosa.es\/blog\/#organization"},"alternateName":"Ado blog corporativo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adosa.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.adosa.es\/blog\/#organization","name":"ADO Blog","url":"https:\/\/www.adosa.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.adosa.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2023\/10\/ado.png","contentUrl":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2023\/10\/ado.png","width":193,"height":101,"caption":"ADO Blog"},"image":{"@id":"https:\/\/www.adosa.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adobcn1\/","https:\/\/x.com\/Adobcn","https:\/\/www.instagram.com\/ado_cerramientos_metalicos\/","https:\/\/www.flickr.com\/photos\/adocerramientosmetalicos","https:\/\/www.pinterest.es\/adocerramientos\/","https:\/\/www.linkedin.com\/company\/2141531\/admin\/feed\/posts\/","https:\/\/www.youtube.com\/user\/adosa2010"]},{"@type":"Person","@id":"https:\/\/www.adosa.es\/blog\/#\/schema\/person\/81eafc1325fbcc103884a7dfefe3802d","name":"adosa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g","caption":"adosa"},"sameAs":["https:\/\/www.adosa.es\/blog"],"url":"https:\/\/www.adosa.es\/blog\/author\/adosa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/posts\/6700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/comments?post=6700"}],"version-history":[{"count":1,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/posts\/6700\/revisions"}],"predecessor-version":[{"id":6704,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/posts\/6700\/revisions\/6704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/media\/6701"}],"wp:attachment":[{"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/media?parent=6700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/categories?post=6700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/tags?post=6700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}