{"id":4932,"date":"2022-11-21T12:00:25","date_gmt":"2022-11-21T10:00:25","guid":{"rendered":"https:\/\/www.adosa.es\/blog\/?p=4932"},"modified":"2023-10-17T17:10:10","modified_gmt":"2023-10-17T15:10:10","slug":"pilonas-urbanas-protec-instaladas","status":"publish","type":"post","link":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/","title":{"rendered":"Pilonas urbanas Protec instaladas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Pilonas Protec amarillas con cinta adhesiva en negro instaladas. Instaladas en entradas y salidas de colegios para proporcionar seguridad a los peatones.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2022\/11\/pilonas-protec-1024x1024.jpg\" alt=\"pilonas protec amarillas\" class=\"wp-image-4933\" title=\"pilonas protec amarillas\" srcset=\"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2022\/11\/pilonas-protec-1024x1024.jpg 1024w, https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2022\/11\/pilonas-protec-300x300.jpg 300w, https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2022\/11\/pilonas-protec-150x150.jpg 150w, https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2022\/11\/pilonas-protec-768x768.jpg 768w, https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2022\/11\/pilonas-protec.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.adosa.es\/pilona-protec.html\">M\u00e1s informaci\u00f3n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pilonas Protec amarillas con cinta adhesiva en negro instaladas. Instaladas en entradas y salidas de colegios para proporcionar seguridad a los peatones.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,159],"tags":[607,608,609],"class_list":["post-4932","post","type-post","status-publish","format-standard","hentry","category-mobiliario-urbano","category-pilonas-fijas","tag-camino-escolar","tag-pilona-protec","tag-pilonas-amarillas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pilonas urbanas Protec instaladas - ADO Blog<\/title>\n<meta name=\"description\" content=\"Pilonas Protec amarillas con cinta adhesiva en negro instaladas en entradas y salidas de colegios para proporcionar seguridad a los peatones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pilonas urbanas Protec instaladas - ADO Blog\" \/>\n<meta property=\"og:description\" content=\"Pilonas Protec amarillas con cinta adhesiva en negro instaladas en entradas y salidas de colegios para proporcionar seguridad a los peatones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/\" \/>\n<meta property=\"og:site_name\" content=\"ADO Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adobcn1\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-21T10:00:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-17T15:10:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2022\/11\/pilonas-protec-1024x1024.jpg\" \/>\n<meta name=\"author\" content=\"adosa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Adobcn\" \/>\n<meta name=\"twitter:site\" content=\"@Adobcn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/pilonas-urbanas-protec-instaladas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/pilonas-urbanas-protec-instaladas\\\/\"},\"author\":{\"name\":\"adosa\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#\\\/schema\\\/person\\\/81eafc1325fbcc103884a7dfefe3802d\"},\"headline\":\"Pilonas urbanas Protec instaladas\",\"datePublished\":\"2022-11-21T10:00:25+00:00\",\"dateModified\":\"2023-10-17T15:10:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/pilonas-urbanas-protec-instaladas\\\/\"},\"wordCount\":30,\"publisher\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/pilonas-urbanas-protec-instaladas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/pilonas-protec-1024x1024.jpg\",\"keywords\":[\"camino escolar\",\"pilona protec\",\"pilonas amarillas\"],\"articleSection\":[\"Mobiliario Urbano\",\"Pilonas Fijas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/pilonas-urbanas-protec-instaladas\\\/\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/pilonas-urbanas-protec-instaladas\\\/\",\"name\":\"Pilonas urbanas Protec instaladas - ADO Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/pilonas-urbanas-protec-instaladas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/pilonas-urbanas-protec-instaladas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/pilonas-protec-1024x1024.jpg\",\"datePublished\":\"2022-11-21T10:00:25+00:00\",\"dateModified\":\"2023-10-17T15:10:10+00:00\",\"description\":\"Pilonas Protec amarillas con cinta adhesiva en negro instaladas en entradas y salidas de colegios para proporcionar seguridad a los peatones.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/pilonas-urbanas-protec-instaladas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.adosa.es\\\/blog\\\/pilonas-urbanas-protec-instaladas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/pilonas-urbanas-protec-instaladas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/pilonas-protec.jpg\",\"contentUrl\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/pilonas-protec.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/pilonas-urbanas-protec-instaladas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pilonas urbanas Protec instaladas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/\",\"name\":\"ADO Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#organization\"},\"alternateName\":\"Ado blog corporativo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#organization\",\"name\":\"ADO Blog\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ado.png\",\"contentUrl\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ado.png\",\"width\":193,\"height\":101,\"caption\":\"ADO Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adobcn1\\\/\",\"https:\\\/\\\/x.com\\\/Adobcn\",\"https:\\\/\\\/www.instagram.com\\\/ado_cerramientos_metalicos\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/adocerramientosmetalicos\",\"https:\\\/\\\/www.pinterest.es\\\/adocerramientos\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2141531\\\/admin\\\/feed\\\/posts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/adosa2010\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#\\\/schema\\\/person\\\/81eafc1325fbcc103884a7dfefe3802d\",\"name\":\"adosa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g\",\"caption\":\"adosa\"},\"sameAs\":[\"https:\\\/\\\/www.adosa.es\\\/blog\"],\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/author\\\/adosa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pilonas urbanas Protec instaladas - ADO Blog","description":"Pilonas Protec amarillas con cinta adhesiva en negro instaladas en entradas y salidas de colegios para proporcionar seguridad a los peatones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/","og_locale":"es_ES","og_type":"article","og_title":"Pilonas urbanas Protec instaladas - ADO Blog","og_description":"Pilonas Protec amarillas con cinta adhesiva en negro instaladas en entradas y salidas de colegios para proporcionar seguridad a los peatones.","og_url":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/","og_site_name":"ADO Blog","article_publisher":"https:\/\/www.facebook.com\/adobcn1\/","article_published_time":"2022-11-21T10:00:25+00:00","article_modified_time":"2023-10-17T15:10:10+00:00","og_image":[{"url":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2022\/11\/pilonas-protec-1024x1024.jpg","type":"","width":"","height":""}],"author":"adosa","twitter_card":"summary_large_image","twitter_creator":"@Adobcn","twitter_site":"@Adobcn","twitter_misc":{"Escrito por":"adosa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/#article","isPartOf":{"@id":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/"},"author":{"name":"adosa","@id":"https:\/\/www.adosa.es\/blog\/#\/schema\/person\/81eafc1325fbcc103884a7dfefe3802d"},"headline":"Pilonas urbanas Protec instaladas","datePublished":"2022-11-21T10:00:25+00:00","dateModified":"2023-10-17T15:10:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/"},"wordCount":30,"publisher":{"@id":"https:\/\/www.adosa.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2022\/11\/pilonas-protec-1024x1024.jpg","keywords":["camino escolar","pilona protec","pilonas amarillas"],"articleSection":["Mobiliario Urbano","Pilonas Fijas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/","url":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/","name":"Pilonas urbanas Protec instaladas - ADO Blog","isPartOf":{"@id":"https:\/\/www.adosa.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/#primaryimage"},"image":{"@id":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2022\/11\/pilonas-protec-1024x1024.jpg","datePublished":"2022-11-21T10:00:25+00:00","dateModified":"2023-10-17T15:10:10+00:00","description":"Pilonas Protec amarillas con cinta adhesiva en negro instaladas en entradas y salidas de colegios para proporcionar seguridad a los peatones.","breadcrumb":{"@id":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/#primaryimage","url":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2022\/11\/pilonas-protec.jpg","contentUrl":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2022\/11\/pilonas-protec.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.adosa.es\/blog\/pilonas-urbanas-protec-instaladas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.adosa.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Pilonas urbanas Protec instaladas"}]},{"@type":"WebSite","@id":"https:\/\/www.adosa.es\/blog\/#website","url":"https:\/\/www.adosa.es\/blog\/","name":"ADO Blog","description":"","publisher":{"@id":"https:\/\/www.adosa.es\/blog\/#organization"},"alternateName":"Ado blog corporativo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adosa.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.adosa.es\/blog\/#organization","name":"ADO Blog","url":"https:\/\/www.adosa.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.adosa.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2023\/10\/ado.png","contentUrl":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2023\/10\/ado.png","width":193,"height":101,"caption":"ADO Blog"},"image":{"@id":"https:\/\/www.adosa.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adobcn1\/","https:\/\/x.com\/Adobcn","https:\/\/www.instagram.com\/ado_cerramientos_metalicos\/","https:\/\/www.flickr.com\/photos\/adocerramientosmetalicos","https:\/\/www.pinterest.es\/adocerramientos\/","https:\/\/www.linkedin.com\/company\/2141531\/admin\/feed\/posts\/","https:\/\/www.youtube.com\/user\/adosa2010"]},{"@type":"Person","@id":"https:\/\/www.adosa.es\/blog\/#\/schema\/person\/81eafc1325fbcc103884a7dfefe3802d","name":"adosa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g","caption":"adosa"},"sameAs":["https:\/\/www.adosa.es\/blog"],"url":"https:\/\/www.adosa.es\/blog\/author\/adosa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/posts\/4932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/comments?post=4932"}],"version-history":[{"count":1,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/posts\/4932\/revisions"}],"predecessor-version":[{"id":5493,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/posts\/4932\/revisions\/5493"}],"wp:attachment":[{"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/media?parent=4932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/categories?post=4932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/tags?post=4932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}