{"id":224,"date":"2011-05-20T13:15:04","date_gmt":"2011-05-20T13:15:04","guid":{"rendered":"http:\/\/www.adosa.es\/\/blog\/?p=224"},"modified":"2023-10-20T13:38:32","modified_gmt":"2023-10-20T11:38:32","slug":"instalacion-bancos-novela-en-santa-coloma-de-gramanet","status":"publish","type":"post","link":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/","title":{"rendered":"Bancos urbanos Novela en acero inoxidable"},"content":{"rendered":"\n<div class=\"mceTemp\">\n<p>El ayuntamiento de Santa Coloma de Gramenet, a&nbsp;elegido nuestro modelo&nbsp;<strong>Banco Novela<\/strong> en acero inoxidable compuesto de 6 listones de madera tropical con extructura en forma de V.<\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large size-full wp-image-225\"><img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"396\" data-id=\"225\" src=\"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2011\/05\/BANCO_NOVELA.gif\" alt=\"Bancos en acero inoxidable Novela\" class=\"wp-image-225\"\/><figcaption class=\"wp-element-caption\">Varios ayuntamientos ya han elegido nuestro banco Novela gracias a su dise\u00f1o y funcionalidad.<\/figcaption><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El ayuntamiento de Santa Coloma de Gramenet, a&nbsp;elegido nuestro modelo&nbsp;Banco Novela en acero inoxidable compuesto de 6 listones de madera tropical con extructura en forma de V.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,13,78],"tags":[23,24],"class_list":["post-224","post","type-post","status-publish","format-standard","hentry","category-mobiliario-urbano","category-instalaciones","category-bancos-urbanos-mobiliario-urbano-ado","tag-banco-acero-inox","tag-banco-novela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bancos urbanos Novela en acero inoxidable - ADO Blog<\/title>\n<meta name=\"description\" content=\"El ayuntamiento de Santa Coloma de Gramenet ha elegido nuestro modelo de Novela de bancos en acero inoxidable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bancos urbanos Novela en acero inoxidable - ADO Blog\" \/>\n<meta property=\"og:description\" content=\"El ayuntamiento de Santa Coloma de Gramenet ha elegido nuestro modelo de Novela de bancos en acero inoxidable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/\" \/>\n<meta property=\"og:site_name\" content=\"ADO Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adobcn1\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-20T13:15:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-20T11:38:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2011\/05\/BANCO_NOVELA.gif\" \/>\n<meta name=\"author\" content=\"adosa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Adobcn\" \/>\n<meta name=\"twitter:site\" content=\"@Adobcn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\\\/\"},\"author\":{\"name\":\"adosa\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#\\\/schema\\\/person\\\/81eafc1325fbcc103884a7dfefe3802d\"},\"headline\":\"Bancos urbanos Novela en acero inoxidable\",\"datePublished\":\"2011-05-20T13:15:04+00:00\",\"dateModified\":\"2023-10-20T11:38:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\\\/\"},\"wordCount\":51,\"publisher\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/BANCO_NOVELA.gif\",\"keywords\":[\"banco acero inox\",\"banco novela\"],\"articleSection\":[\"Mobiliario Urbano\",\"Instalaciones\",\"Bancos urbanos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\\\/\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\\\/\",\"name\":\"Bancos urbanos Novela en acero inoxidable - ADO Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/BANCO_NOVELA.gif\",\"datePublished\":\"2011-05-20T13:15:04+00:00\",\"dateModified\":\"2023-10-20T11:38:32+00:00\",\"description\":\"El ayuntamiento de Santa Coloma de Gramenet ha elegido nuestro modelo de Novela de bancos en acero inoxidable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.adosa.es\\\/blog\\\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/BANCO_NOVELA.gif\",\"contentUrl\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/BANCO_NOVELA.gif\",\"width\":650,\"height\":396,\"caption\":\"Varios ayuntamientos ya han elegido nuestro banco Novela gracias a su dise\u00f1o y funcionalidad.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bancos urbanos Novela en acero inoxidable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/\",\"name\":\"ADO Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#organization\"},\"alternateName\":\"Ado blog corporativo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#organization\",\"name\":\"ADO Blog\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ado.png\",\"contentUrl\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ado.png\",\"width\":193,\"height\":101,\"caption\":\"ADO Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adobcn1\\\/\",\"https:\\\/\\\/x.com\\\/Adobcn\",\"https:\\\/\\\/www.instagram.com\\\/ado_cerramientos_metalicos\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/adocerramientosmetalicos\",\"https:\\\/\\\/www.pinterest.es\\\/adocerramientos\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2141531\\\/admin\\\/feed\\\/posts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/adosa2010\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/#\\\/schema\\\/person\\\/81eafc1325fbcc103884a7dfefe3802d\",\"name\":\"adosa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g\",\"caption\":\"adosa\"},\"sameAs\":[\"https:\\\/\\\/www.adosa.es\\\/blog\"],\"url\":\"https:\\\/\\\/www.adosa.es\\\/blog\\\/author\\\/adosa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bancos urbanos Novela en acero inoxidable - ADO Blog","description":"El ayuntamiento de Santa Coloma de Gramenet ha elegido nuestro modelo de Novela de bancos en acero inoxidable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/","og_locale":"es_ES","og_type":"article","og_title":"Bancos urbanos Novela en acero inoxidable - ADO Blog","og_description":"El ayuntamiento de Santa Coloma de Gramenet ha elegido nuestro modelo de Novela de bancos en acero inoxidable.","og_url":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/","og_site_name":"ADO Blog","article_publisher":"https:\/\/www.facebook.com\/adobcn1\/","article_published_time":"2011-05-20T13:15:04+00:00","article_modified_time":"2023-10-20T11:38:32+00:00","og_image":[{"url":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2011\/05\/BANCO_NOVELA.gif","type":"","width":"","height":""}],"author":"adosa","twitter_card":"summary_large_image","twitter_creator":"@Adobcn","twitter_site":"@Adobcn","twitter_misc":{"Escrito por":"adosa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/#article","isPartOf":{"@id":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/"},"author":{"name":"adosa","@id":"https:\/\/www.adosa.es\/blog\/#\/schema\/person\/81eafc1325fbcc103884a7dfefe3802d"},"headline":"Bancos urbanos Novela en acero inoxidable","datePublished":"2011-05-20T13:15:04+00:00","dateModified":"2023-10-20T11:38:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/"},"wordCount":51,"publisher":{"@id":"https:\/\/www.adosa.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2011\/05\/BANCO_NOVELA.gif","keywords":["banco acero inox","banco novela"],"articleSection":["Mobiliario Urbano","Instalaciones","Bancos urbanos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/","url":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/","name":"Bancos urbanos Novela en acero inoxidable - ADO Blog","isPartOf":{"@id":"https:\/\/www.adosa.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/#primaryimage"},"image":{"@id":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2011\/05\/BANCO_NOVELA.gif","datePublished":"2011-05-20T13:15:04+00:00","dateModified":"2023-10-20T11:38:32+00:00","description":"El ayuntamiento de Santa Coloma de Gramenet ha elegido nuestro modelo de Novela de bancos en acero inoxidable.","breadcrumb":{"@id":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/#primaryimage","url":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2011\/05\/BANCO_NOVELA.gif","contentUrl":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2011\/05\/BANCO_NOVELA.gif","width":650,"height":396,"caption":"Varios ayuntamientos ya han elegido nuestro banco Novela gracias a su dise\u00f1o y funcionalidad."},{"@type":"BreadcrumbList","@id":"https:\/\/www.adosa.es\/blog\/instalacion-bancos-novela-en-santa-coloma-de-gramanet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.adosa.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Bancos urbanos Novela en acero inoxidable"}]},{"@type":"WebSite","@id":"https:\/\/www.adosa.es\/blog\/#website","url":"https:\/\/www.adosa.es\/blog\/","name":"ADO Blog","description":"","publisher":{"@id":"https:\/\/www.adosa.es\/blog\/#organization"},"alternateName":"Ado blog corporativo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adosa.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.adosa.es\/blog\/#organization","name":"ADO Blog","url":"https:\/\/www.adosa.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.adosa.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2023\/10\/ado.png","contentUrl":"https:\/\/www.adosa.es\/blog\/wp-content\/uploads\/2023\/10\/ado.png","width":193,"height":101,"caption":"ADO Blog"},"image":{"@id":"https:\/\/www.adosa.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adobcn1\/","https:\/\/x.com\/Adobcn","https:\/\/www.instagram.com\/ado_cerramientos_metalicos\/","https:\/\/www.flickr.com\/photos\/adocerramientosmetalicos","https:\/\/www.pinterest.es\/adocerramientos\/","https:\/\/www.linkedin.com\/company\/2141531\/admin\/feed\/posts\/","https:\/\/www.youtube.com\/user\/adosa2010"]},{"@type":"Person","@id":"https:\/\/www.adosa.es\/blog\/#\/schema\/person\/81eafc1325fbcc103884a7dfefe3802d","name":"adosa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6d888f49f452edf67f2cba46f345d128154016f2e15749dd5b837e034803083?s=96&d=mm&r=g","caption":"adosa"},"sameAs":["https:\/\/www.adosa.es\/blog"],"url":"https:\/\/www.adosa.es\/blog\/author\/adosa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/posts\/224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/comments?post=224"}],"version-history":[{"count":1,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/posts\/224\/revisions"}],"predecessor-version":[{"id":6048,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/posts\/224\/revisions\/6048"}],"wp:attachment":[{"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/media?parent=224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/categories?post=224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adosa.es\/blog\/wp-json\/wp\/v2\/tags?post=224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}